{"id":3020,"date":"2024-05-24T12:15:05","date_gmt":"2024-05-24T05:15:05","guid":{"rendered":"https:\/\/plizz.co\/?p=3020"},"modified":"2024-05-24T12:17:18","modified_gmt":"2024-05-24T05:17:18","slug":"thailand-plans-to-ban-recreational-cannabis-despite-2022-decriminalization","status":"publish","type":"post","link":"https:\/\/plizz.co\/th\/blog\/thailand-plans-to-ban-recreational-cannabis-despite-2022-decriminalization\/","title":{"rendered":"Thailand plans to ban recreational cannabis despite 2022 decriminalization"},"content":{"rendered":"<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/plizz.co\/wp-content\/uploads\/2024\/05\/2.9.24_AdobeStock_498448718-1024x576.webp\" alt=\"2.9.24 AdobeStock 498448718\" class=\"wp-image-3022\" srcset=\"https:\/\/plizz.co\/wp-content\/uploads\/2024\/05\/2.9.24_AdobeStock_498448718-1024x576.webp 1024w, https:\/\/plizz.co\/wp-content\/uploads\/2024\/05\/2.9.24_AdobeStock_498448718-300x169.webp 300w, https:\/\/plizz.co\/wp-content\/uploads\/2024\/05\/2.9.24_AdobeStock_498448718-768x432.webp 768w, https:\/\/plizz.co\/wp-content\/uploads\/2024\/05\/2.9.24_AdobeStock_498448718-18x10.webp 18w, https:\/\/plizz.co\/wp-content\/uploads\/2024\/05\/2.9.24_AdobeStock_498448718.webp 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>May 23, 2024<\/p>\n\n\n\n<p>In a major policy reversal, Thailand plans to reclassify cannabis as an illegal substance and issue permits only for medical patients, cultivators and research purposes.<\/p>\n\n\n\n<p>Recreational cannabis use&nbsp;<a href=\"https:\/\/www.reuters.com\/world\/asia-pacific\/thailand-plans-require-permits-medical-research-use-cannabis-2024-05-23\/\" target=\"_blank\" rel=\"noreferrer noopener\">will be banned<\/a>, Public Health Minister Somsak Thepsutin said in a Facebook post, Reuters reported.<\/p>\n\n\n\n<p>Thepsutin\u2019s comments came only weeks after Prime Minister Srettha Thavisin called on the health minister to&nbsp;<a href=\"https:\/\/mjbizdaily.com\/thailand-prime-minister-thavisin-wants-recreational-cannabis-outlawed\/\" target=\"_blank\" rel=\"noreferrer noopener\">reclassify recreational cannabis&nbsp;<\/a>as an illegal substance.<\/p>\n\n\n\n<p>According to the Bangkok Post, Thepsutin also said that only&nbsp;<a href=\"https:\/\/www.bangkokpost.com\/thailand\/general\/2798237\/cannabis-permit-system-in-pipeline\" target=\"_blank\" rel=\"noreferrer noopener\">marijuana buds would be reclassified<\/a>&nbsp;as a Category 5 narcotic.<\/p>\n\n\n\n<p>Category 5 drugs, which include opium and psilocybin, carry criminal penalties in Thailand for manufacturing, importing, exporting, sale and possession.<\/p>\n\n\n\n<p>Marijuana leaves, branches, roots, stems and seeds still would be available to use for approved health and medical applications, Thepsutin said.<\/p>\n\n\n\n<p>Hemp, which was also removed from the Category 5 list, will not face similar restrictions.<\/p>\n\n\n\n<p>The new policy essentially will reverse Thailand\u2019s 2022 move to decriminalize marijuana, though the Asian country failed to immediately implement comprehensive regulations and enforcement mechanisms to restrict what would be sold and where.<\/p>\n\n\n\n<p>Amid a largely unchecked marketplace, thousands of stores opened, prompting politicians to pledge to address the issue.<\/p>\n\n\n\n<p>The policy reversal has&nbsp;<a href=\"https:\/\/thethaiger.com\/news\/national\/cannabis-crackdown-only-buds-back-on-the-blacklist#google_vignette\" target=\"_blank\" rel=\"noreferrer noopener\">sparked widespread&nbsp;protests<\/a>&nbsp;from cannabis advocacy groups, including store owners, Thaiger reported.<\/p>\n\n\n\n<p>Shortly after taking office, Thavisin vowed\u00a0<a href=\"https:\/\/www.youtube.com\/watch?v=5uLzIY6y8Kc\" target=\"_blank\" rel=\"noreferrer noopener\">to rewrite cannabis laws<\/a>\u00a0that would allow only medical use in Thailand, the first Asian nation to decriminalize marijuana.<\/p>\n\n\n\n<p>Source: <a href=\"https:\/\/mjbizdaily.com\/thailand-plans-to-ban-recreational-cannabis-after-2022-decriminalization\/\">MJBizDaily<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>May 23, 2024 In a major policy reversal, Thailand plans to reclassify cannabis as an illegal substance and issue permits only for medical patients, cultivators and research purposes. Recreational cannabis use&nbsp;will be banned, Public Health Minister Somsak Thepsutin said in a Facebook post, Reuters reported. Thepsutin\u2019s comments came only weeks after Prime Minister Srettha Thavisin [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":3022,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3020","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Thailand plans to ban recreational cannabis despite 2022 decriminalization<\/title>\n<meta name=\"description\" content=\"Read our article &quot; Thailand plans to ban recreational cannabis despite 2022 decriminalization &quot;. Dive into our blog for insights on accounting, legal services, and tips specifically crafted for SMEs in Thailand.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/plizz.co\/th\/blog\/thailand-plans-to-ban-recreational-cannabis-despite-2022-decriminalization\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Thailand plans to ban recreational cannabis despite 2022 decriminalization\" \/>\n<meta property=\"og:description\" content=\"Read our article &quot; Thailand plans to ban recreational cannabis despite 2022 decriminalization &quot;. Dive into our blog for insights on accounting, legal services, and tips specifically crafted for SMEs in Thailand.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/plizz.co\/th\/blog\/thailand-plans-to-ban-recreational-cannabis-despite-2022-decriminalization\/\" \/>\n<meta property=\"og:site_name\" content=\"Plizz\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-24T05:15:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-24T05:17:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/plizz.co\/wp-content\/uploads\/2024\/05\/2.9.24_AdobeStock_498448718.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Adrien Touchet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Adrien Touchet\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/plizz.co\/blog\/thailand-plans-to-ban-recreational-cannabis-despite-2022-decriminalization\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/plizz.co\/blog\/thailand-plans-to-ban-recreational-cannabis-despite-2022-decriminalization\/\"},\"author\":{\"name\":\"Adrien Touchet\",\"@id\":\"https:\/\/plizz.co\/#\/schema\/person\/9bb57c7d1344e0f884a835f1d43068af\"},\"headline\":\"Thailand plans to ban recreational cannabis despite 2022 decriminalization\",\"datePublished\":\"2024-05-24T05:15:05+00:00\",\"dateModified\":\"2024-05-24T05:17:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/plizz.co\/blog\/thailand-plans-to-ban-recreational-cannabis-despite-2022-decriminalization\/\"},\"wordCount\":250,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/plizz.co\/#organization\"},\"image\":{\"@id\":\"https:\/\/plizz.co\/blog\/thailand-plans-to-ban-recreational-cannabis-despite-2022-decriminalization\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/plizz.co\/wp-content\/uploads\/2024\/05\/2.9.24_AdobeStock_498448718.webp\",\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/plizz.co\/blog\/thailand-plans-to-ban-recreational-cannabis-despite-2022-decriminalization\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/plizz.co\/blog\/thailand-plans-to-ban-recreational-cannabis-despite-2022-decriminalization\/\",\"url\":\"https:\/\/plizz.co\/blog\/thailand-plans-to-ban-recreational-cannabis-despite-2022-decriminalization\/\",\"name\":\"Thailand plans to ban recreational cannabis despite 2022 decriminalization\",\"isPartOf\":{\"@id\":\"https:\/\/plizz.co\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/plizz.co\/blog\/thailand-plans-to-ban-recreational-cannabis-despite-2022-decriminalization\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/plizz.co\/blog\/thailand-plans-to-ban-recreational-cannabis-despite-2022-decriminalization\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/plizz.co\/wp-content\/uploads\/2024\/05\/2.9.24_AdobeStock_498448718.webp\",\"datePublished\":\"2024-05-24T05:15:05+00:00\",\"dateModified\":\"2024-05-24T05:17:18+00:00\",\"description\":\"Read our article \\\" Thailand plans to ban recreational cannabis despite 2022 decriminalization \\\". Dive into our blog for insights on accounting, legal services, and tips specifically crafted for SMEs in Thailand.\",\"breadcrumb\":{\"@id\":\"https:\/\/plizz.co\/blog\/thailand-plans-to-ban-recreational-cannabis-despite-2022-decriminalization\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/plizz.co\/blog\/thailand-plans-to-ban-recreational-cannabis-despite-2022-decriminalization\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\/\/plizz.co\/blog\/thailand-plans-to-ban-recreational-cannabis-despite-2022-decriminalization\/#primaryimage\",\"url\":\"https:\/\/plizz.co\/wp-content\/uploads\/2024\/05\/2.9.24_AdobeStock_498448718.webp\",\"contentUrl\":\"https:\/\/plizz.co\/wp-content\/uploads\/2024\/05\/2.9.24_AdobeStock_498448718.webp\",\"width\":1280,\"height\":720,\"caption\":\"2.9.24 AdobeStock 498448718\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/plizz.co\/blog\/thailand-plans-to-ban-recreational-cannabis-despite-2022-decriminalization\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Uncategorized\",\"item\":\"https:\/\/plizz.co\/blog\/category\/uncategorized\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Thailand plans to ban recreational cannabis despite 2022 decriminalization\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/plizz.co\/#website\",\"url\":\"https:\/\/plizz.co\/\",\"name\":\"Plizz\",\"description\":\"Accounting &amp; Legal services for SMEs\",\"publisher\":{\"@id\":\"https:\/\/plizz.co\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/plizz.co\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/plizz.co\/#organization\",\"name\":\"Plizz\",\"url\":\"https:\/\/plizz.co\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\/\/plizz.co\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/plizz.co\/wp-content\/uploads\/2021\/11\/plizz-logo.png\",\"contentUrl\":\"https:\/\/plizz.co\/wp-content\/uploads\/2021\/11\/plizz-logo.png\",\"width\":700,\"height\":300,\"caption\":\"Plizz\"},\"image\":{\"@id\":\"https:\/\/plizz.co\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/plizz.co\/#\/schema\/person\/9bb57c7d1344e0f884a835f1d43068af\",\"name\":\"Adrien Touchet\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\/\/plizz.co\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8d705075bb79c7b8a88bfeb5109689e9f286a591117a73f1a931241cc1c66135?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8d705075bb79c7b8a88bfeb5109689e9f286a591117a73f1a931241cc1c66135?s=96&d=mm&r=g\",\"caption\":\"Adrien Touchet\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Thailand plans to ban recreational cannabis despite 2022 decriminalization","description":"Read our article \" Thailand plans to ban recreational cannabis despite 2022 decriminalization \". Dive into our blog for insights on accounting, legal services, and tips specifically crafted for SMEs in Thailand.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/plizz.co\/th\/blog\/thailand-plans-to-ban-recreational-cannabis-despite-2022-decriminalization\/","og_locale":"th_TH","og_type":"article","og_title":"Thailand plans to ban recreational cannabis despite 2022 decriminalization","og_description":"Read our article \" Thailand plans to ban recreational cannabis despite 2022 decriminalization \". Dive into our blog for insights on accounting, legal services, and tips specifically crafted for SMEs in Thailand.","og_url":"https:\/\/plizz.co\/th\/blog\/thailand-plans-to-ban-recreational-cannabis-despite-2022-decriminalization\/","og_site_name":"Plizz","article_published_time":"2024-05-24T05:15:05+00:00","article_modified_time":"2024-05-24T05:17:18+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/plizz.co\/wp-content\/uploads\/2024\/05\/2.9.24_AdobeStock_498448718.webp","type":"image\/webp"}],"author":"Adrien Touchet","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Adrien Touchet","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/plizz.co\/blog\/thailand-plans-to-ban-recreational-cannabis-despite-2022-decriminalization\/#article","isPartOf":{"@id":"https:\/\/plizz.co\/blog\/thailand-plans-to-ban-recreational-cannabis-despite-2022-decriminalization\/"},"author":{"name":"Adrien Touchet","@id":"https:\/\/plizz.co\/#\/schema\/person\/9bb57c7d1344e0f884a835f1d43068af"},"headline":"Thailand plans to ban recreational cannabis despite 2022 decriminalization","datePublished":"2024-05-24T05:15:05+00:00","dateModified":"2024-05-24T05:17:18+00:00","mainEntityOfPage":{"@id":"https:\/\/plizz.co\/blog\/thailand-plans-to-ban-recreational-cannabis-despite-2022-decriminalization\/"},"wordCount":250,"commentCount":0,"publisher":{"@id":"https:\/\/plizz.co\/#organization"},"image":{"@id":"https:\/\/plizz.co\/blog\/thailand-plans-to-ban-recreational-cannabis-despite-2022-decriminalization\/#primaryimage"},"thumbnailUrl":"https:\/\/plizz.co\/wp-content\/uploads\/2024\/05\/2.9.24_AdobeStock_498448718.webp","inLanguage":"th","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/plizz.co\/blog\/thailand-plans-to-ban-recreational-cannabis-despite-2022-decriminalization\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/plizz.co\/blog\/thailand-plans-to-ban-recreational-cannabis-despite-2022-decriminalization\/","url":"https:\/\/plizz.co\/blog\/thailand-plans-to-ban-recreational-cannabis-despite-2022-decriminalization\/","name":"Thailand plans to ban recreational cannabis despite 2022 decriminalization","isPartOf":{"@id":"https:\/\/plizz.co\/#website"},"primaryImageOfPage":{"@id":"https:\/\/plizz.co\/blog\/thailand-plans-to-ban-recreational-cannabis-despite-2022-decriminalization\/#primaryimage"},"image":{"@id":"https:\/\/plizz.co\/blog\/thailand-plans-to-ban-recreational-cannabis-despite-2022-decriminalization\/#primaryimage"},"thumbnailUrl":"https:\/\/plizz.co\/wp-content\/uploads\/2024\/05\/2.9.24_AdobeStock_498448718.webp","datePublished":"2024-05-24T05:15:05+00:00","dateModified":"2024-05-24T05:17:18+00:00","description":"Read our article \" Thailand plans to ban recreational cannabis despite 2022 decriminalization \". Dive into our blog for insights on accounting, legal services, and tips specifically crafted for SMEs in Thailand.","breadcrumb":{"@id":"https:\/\/plizz.co\/blog\/thailand-plans-to-ban-recreational-cannabis-despite-2022-decriminalization\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/plizz.co\/blog\/thailand-plans-to-ban-recreational-cannabis-despite-2022-decriminalization\/"]}]},{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/plizz.co\/blog\/thailand-plans-to-ban-recreational-cannabis-despite-2022-decriminalization\/#primaryimage","url":"https:\/\/plizz.co\/wp-content\/uploads\/2024\/05\/2.9.24_AdobeStock_498448718.webp","contentUrl":"https:\/\/plizz.co\/wp-content\/uploads\/2024\/05\/2.9.24_AdobeStock_498448718.webp","width":1280,"height":720,"caption":"2.9.24 AdobeStock 498448718"},{"@type":"BreadcrumbList","@id":"https:\/\/plizz.co\/blog\/thailand-plans-to-ban-recreational-cannabis-despite-2022-decriminalization\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Uncategorized","item":"https:\/\/plizz.co\/blog\/category\/uncategorized\/"},{"@type":"ListItem","position":2,"name":"Thailand plans to ban recreational cannabis despite 2022 decriminalization"}]},{"@type":"WebSite","@id":"https:\/\/plizz.co\/#website","url":"https:\/\/plizz.co\/","name":"Plizz","description":"Accounting &amp; Legal services for SMEs","publisher":{"@id":"https:\/\/plizz.co\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/plizz.co\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"},{"@type":"Organization","@id":"https:\/\/plizz.co\/#organization","name":"Plizz","url":"https:\/\/plizz.co\/","logo":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/plizz.co\/#\/schema\/logo\/image\/","url":"https:\/\/plizz.co\/wp-content\/uploads\/2021\/11\/plizz-logo.png","contentUrl":"https:\/\/plizz.co\/wp-content\/uploads\/2021\/11\/plizz-logo.png","width":700,"height":300,"caption":"Plizz"},"image":{"@id":"https:\/\/plizz.co\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/plizz.co\/#\/schema\/person\/9bb57c7d1344e0f884a835f1d43068af","name":"Adrien Touchet","image":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/plizz.co\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8d705075bb79c7b8a88bfeb5109689e9f286a591117a73f1a931241cc1c66135?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8d705075bb79c7b8a88bfeb5109689e9f286a591117a73f1a931241cc1c66135?s=96&d=mm&r=g","caption":"Adrien Touchet"}}]}},"_links":{"self":[{"href":"https:\/\/plizz.co\/th\/wp-json\/wp\/v2\/posts\/3020","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plizz.co\/th\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plizz.co\/th\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plizz.co\/th\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/plizz.co\/th\/wp-json\/wp\/v2\/comments?post=3020"}],"version-history":[{"count":2,"href":"https:\/\/plizz.co\/th\/wp-json\/wp\/v2\/posts\/3020\/revisions"}],"predecessor-version":[{"id":3023,"href":"https:\/\/plizz.co\/th\/wp-json\/wp\/v2\/posts\/3020\/revisions\/3023"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/plizz.co\/th\/wp-json\/wp\/v2\/media\/3022"}],"wp:attachment":[{"href":"https:\/\/plizz.co\/th\/wp-json\/wp\/v2\/media?parent=3020"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plizz.co\/th\/wp-json\/wp\/v2\/categories?post=3020"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plizz.co\/th\/wp-json\/wp\/v2\/tags?post=3020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}